{"id":24506,"date":"2023-12-10T12:25:58","date_gmt":"2023-12-10T11:25:58","guid":{"rendered":"https:\/\/www.escapade-norvegienne.com\/opphold-med-hundeslede\/sejour-aventure-grand-nord\/"},"modified":"2025-12-17T13:44:57","modified_gmt":"2025-12-17T12:44:57","slug":"eventyr-i-nord","status":"publish","type":"page","link":"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/","title":{"rendered":"Eventyr i Nord"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"24506\" class=\"elementor elementor-24506 elementor-19658\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5a87e401 elementor-section-stretched elementor-section-height-min-height elementor-section-content-bottom elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"5a87e401\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e3e4c82\" data-id=\"e3e4c82\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d67c31b text-flex-end text--mobileflex-start elementor-hidden-mobile elementor-widget elementor-widget-tp-breadcrumbs-bar\" data-id=\"d67c31b\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"tp-breadcrumbs-bar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"bread6a04bc82ab419\" class=\"pt_plus_breadcrumbs_bar \"  \"><div class=\"pt_plus_breadcrumbs_bar_inner bred_style_1\"><nav id=\"breadcrumbs\"><span class=\"bc_home\"><a class=\"home_bread_tab\" href=\"https:\/\/www.escapade-norvegienne.com\/no\/\/\">Accueil<i class=\" fa fa-forward bread-sep-icon\" ><\/i><\/a><\/span> <span class=\"del\"><\/span> <span class=\"current_active\"><div class=\"current_tab_sec\">Side<\/div><\/span><\/nav><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ae37c7 elementor-widget elementor-widget-spacer\" data-id=\"1ae37c7\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-229c0ef6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"229c0ef6\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-733629c9\" data-id=\"733629c9\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3152e360 text-left elementor-widget elementor-widget-tp-heading-title\" data-id=\"3152e360\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"tp-heading-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"heading heading_style heading_style6a04bc82ae46f style-1 \" ><div class=\"sub-style \"  ><div class=\"sub-heading\"><h3 class=\"heading-sub-title  \"> #hundesledeopphold <\/h3><\/div><div class=\"head-title \" > <h2  class=\"heading-title   \"   data-hover=\"Opphold eventyr i Nord\">Opphold eventyr i Nord<span class=\"title-s \">  <\/span><\/h2><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4413b0c9 test elementor-widget elementor-widget-elementskit-heading\" data-id=\"4413b0c9\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-text_left   ekit_heading_mobile- ekit-heading__title-in-left\">\t\t\t\t<div class='ekit-heading__title-wrapper'>\n\t\t\t<h3 class=\"ekit-heading--title elementskit-section-title text_fill\"><span><span>sledehunder<\/span><\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class='ekit-heading__content-wrapper'>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42551a80 text-left elementor-widget elementor-widget-tp-adv-text-block\" data-id=\"42551a80\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"tp-adv-text-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pt-plus-text-block-wrapper\" ><div class=\"text_block_parallax\"><div class=\"pt_plus_adv_text_block \" ><div class=\"text-content-block\"><span style=\"color: #ffffff\">I de sn\u00f8dekte fjellene blir sledeeventyret episk, og tar oss gjennom ur\u00f8rte landskap for \u00e5 erobre det ukjente. Norge og dets frosne innsj\u00f8er gir et perfekt lerret for \u00e5 nyte gledene ved \u00e5 gli, hvor rommet virker uendelig, og de sn\u00f8dekte omr\u00e5dene glitrer av renhet, og skaper uforglemmelige minner. Jean-Philippe, rik p\u00e5 erfaring som langdistansel\u00f8per, vil dele sin lidenskap med deg og f\u00f8lge deg p\u00e5 dette eventyret (maks 4 personer).<\/span>\n<h3><span style=\"color: #ffffff\">VERTENE DINE<\/span><\/h3>\n<p class=\"p1\">St\u00e9phanie Prades &amp; Jean Philippe Pontier \u2013 Hodalsveien 1155 \u2013 N-2540 TOLGA<\/p><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40341364 elementor-widget elementor-widget-elementskit-heading\" data-id=\"40341364\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-text_left   ekit_heading_mobile- ekit-heading__title-in-left\">\t\t\t\t<span class='ekit-heading__shadow-text'>\n\t\t\t\t\tsesong\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<div class='ekit-heading__title-wrapper'>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='ekit-heading__content-wrapper'>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-47e86697 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"47e86697\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-640972df\" data-id=\"640972df\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40cd28f0 ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"40cd28f0\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"#\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-left text-left icon-lef-right-aligin elementor-animation- media  \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  text-center\">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon far fa-calendar-alt\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    22. desember                <\/h3>\n                                            <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d06b765\" data-id=\"d06b765\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ddb7b9e ekit-equal-height-disable elementor-widget elementor-widget-elementskit-icon-box\" data-id=\"4ddb7b9e\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >        <!-- link opening -->\n                <a href=\"#\" class=\"ekit_global_links\">\n                <!-- end link opening -->\n\n        <div class=\"elementskit-infobox text-left text-left icon-lef-right-aligin elementor-animation- media  \">\n                    <div class=\"elementskit-box-header elementor-animation-\">\n                <div class=\"elementskit-info-box-icon  text-center\">\n                    <i aria-hidden=\"true\" class=\"elementkit-infobox-icon far fa-calendar-times\"><\/i>\n                <\/div>\n          <\/div>\n                        <div class=\"box-body\">\n                            <h3 class=\"elementskit-info-box-title\">\n                    30. april                <\/h3>\n                                            <\/div>\n        \n        \n                <\/div>\n                <\/a>\n        <\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-72e2319f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72e2319f\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-10b3222b\" data-id=\"10b3222b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5dc2740c text-left elementor-widget elementor-widget-tp-heading-title\" data-id=\"5dc2740c\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"tp-heading-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"heading heading_style heading_style6a04bc82af92f style-1 \" ><div class=\"sub-style \"  ><div class=\"head-title \" > <h4  class=\"heading-title   \"   data-hover=\"pris for opphold: 1990 NOK\">pris for opphold: 1990 NOK<span class=\"title-s \">  <\/span><\/h4><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-29441174\" data-id=\"29441174\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-621e9bc8 text-left elementor-widget elementor-widget-tp-heading-title\" data-id=\"621e9bc8\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"tp-heading-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"heading heading_style heading_style6a04bc82b0cb7 style-1 \" ><div class=\"sub-style \"  ><div class=\"head-title \" > <h4  class=\"heading-title   \"   data-hover=\"per person\">per person<span class=\"title-s \">  <\/span><\/h4><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ac4b399 elementor-widget elementor-widget-spacer\" data-id=\"7ac4b399\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c75be31\" data-id=\"c75be31\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4dd44475 elementor-widget elementor-widget-spacer\" data-id=\"4dd44475\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6950176a elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6950176a\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6c3f4d5c\" data-id=\"6c3f4d5c\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5420c028 elementor-widget elementor-widget-heading\" data-id=\"5420c028\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Fordeler<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ceb7195 elementor-widget elementor-widget-text-editor\" data-id=\"3ceb7195\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #063b99;\">Eksklusivt for familie eller etablert gruppe (Aldersgrense fra 15 \u00e5r)<\/span><\/p><p><span style=\"color: #063b99;\">30 \u00e5rs erfaring med hunder i konkurranse i Alaska \/ Norge<\/span><\/p><p><span style=\"color: #063b99;\">Utstyr av h\u00f8yeste kvalitet<\/span><\/p><p><span style=\"color: #063b99;\">En helt vill natur<\/span><\/p><p><span style=\"color: #063b99;\">Autentisk gastronomi og gjestfrihet.<\/span><\/p><p><span style=\"color: #063b99;\">En 100% norsk badstue for avslapning<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1596f60 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1596f60\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b5c492b\" data-id=\"b5c492b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41e6cc6b elementor-widget elementor-widget-wp-widget-simple-weather\" data-id=\"41e6cc6b\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"wp-widget-simple-weather.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"simple-weather--e990aaf05934e1e230a317df33993252\" class=\"simple-weather simple-weather--vue\" :style=\"atts.inline_css\">\n  <template v-if=\"style !== 'widget'\">\n    <span v-if=\"hasCurrentWeather()\" class=\"simple-weather__day simple-weather__day--current\">\n      <span v-if=\"filter_var(atts.show_units)\" class=\"simple-weather__date\">{{current_weather.dt | momentjs( atts.date )}}<\/span>\n      <i class=\"sw\" :class=\"getWeatherIcon(current_weather)\"><\/i>\n      <em class=\"simple-weather__temp\">{{current_weather.temp | temp}} &deg;<template v-if=\"filter_var(atts.show_units)\">{{units}}<\/template>\n      <\/em>\n    <\/span>\n    <template v-if=\"weather_feed\">\n      <span v-for=\"(day, index) in weather_feed\" v-if=\"isDayVisible(index, day)\" class=\"simple-weather__day\">\n        <span v-if=\"filter_var(atts.show_units)\" class=\"simple-weather__date\">{{day.dt | momentjs(atts.date)}}<\/span>\n        <i class=\"sw\" :class=\"getWeatherIcon(day)\"><\/i>\n        <em class=\"simple-weather__temp\">{{day.temp | temp}} &deg;<em class=\"simple-weather__temp-min\" v-if=\"filter_var(atts.night)\">{{day.temp_min | temp}} &deg;<\/em><template v-if=\"filter_var(atts.show_units)\">{{units}}<\/template><\/em>\n      <\/span>\n    <\/template>\n    <template v-else>\n      <span v-html=\"error\" class=\"error\"><\/span>\n    <\/template>\n  <\/template>\n  <template v-else>\n    <div class=\"simple-weather-widget\" v-if=\"current_weather.name || weather_feed\" :class=\"atts.inline_css ? 'simple-weather-widget--bg' : ''\">\n      <h4 class='widget_title' v-if=\"atts.title || current_weather.name\" v-text=\"atts.title ? atts.title : current_weather.name\"><\/h4>\n      <div class=\"temp\">\n        <span v-if=\"current_weather.temp\" class=\"degrees\">{{current_weather.temp | temp}} &deg;<\/span>\n        <span class=\"details\">\n          <template v-if=\"current_weather.humidity\">Humidity: <em class=\"float-right\">{{current_weather.humidity}}%<\/em><br><\/template>\n          <template v-if=\"current_weather.clouds\">Clouds: <em class=\"float-right\">{{current_weather.clouds}}%<\/em><br><\/template>\n          <template v-if=\"current_weather.wind\">Wind <small>({{current_weather.wind.deg}})<\/small>:\n          <em class=\"float-right\">{{current_weather.wind.speed}}<small>{{units_wind}}<\/small><\/em><\/template>\n        <\/span>\n      <\/div>\n      <div class=\"summary\">{{current_weather.desc}}<\/div>\n      <div class=\"simple-weather-table\" v-if=\"weather_feed\">\n        <div v-for=\"(day, index) in weather_feed\" v-if=\"index < atts.days\" class=\"simple-weather-table__row\">\n\t\t\t\t\t<div class=\"simple-weather-table__date\">{{day.dt | momentjs(atts.date)}}<\/div>\n\t\t\t\t\t<div class=\"simple-weather-table__icon\"><i class=\"sw\" :class=\"getWeatherIcon(day)\"><\/i><\/div>\n\t\t\t\t\t<div class=\"simple-weather-table__temp\">\n            {{day.temp | temp}}&deg;\n            <span class=\"simple-weather-table__temp-min\">{{day.temp_min | temp}} &deg;<\/span>\n          <\/div>\n        <\/div>\n      <\/div>\n    <\/div>\n  <\/template>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-b807d03\" data-id=\"b807d03\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23af43e6 elementor-widget elementor-widget-image\" data-id=\"23af43e6\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.team-pontier.com\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"697\" src=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/11\/logo-team-pontier.png\" class=\"attachment-large size-large wp-image-17484\" alt=\"\" srcset=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/11\/logo-team-pontier.png 895w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/11\/logo-team-pontier-300x261.png 300w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/11\/logo-team-pontier-768x669.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b68e20c elementor-widget elementor-widget-spacer\" data-id=\"6b68e20c\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2b0c4649\" data-id=\"2b0c4649\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bd81885 elementor-absolute elementor-widget elementor-widget-image\" data-id=\"6bd81885\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/04\/activite-chien-N.png\" class=\"attachment-large size-large wp-image-16485\" alt=\"\" srcset=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/04\/activite-chien-N.png 300w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/04\/activite-chien-N-150x150.png 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55a698d7 elementor-widget elementor-widget-heading\" data-id=\"55a698d7\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ref: Eventyr-i-Nord<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-33bc8aa1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"33bc8aa1\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-e7e90\" data-id=\"e7e90\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30a0a19b elementor-widget elementor-widget-heading\" data-id=\"30a0a19b\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vanskelighetsgrad<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b40c0aa elementor-widget elementor-widget-text-editor\" data-id=\"b40c0aa\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #ff9900;\">\u2605 <span style=\"color: #000000;\">Lett<\/span><\/span><\/p><p><span style=\"color: #ff9900;\">\u2605\u2605 <span style=\"color: #000000;\">Ganske lett<\/span><\/span><\/p><p><span style=\"color: #ff9900;\"><span style=\"color: #0000ff;\">\u2605\u2605\u2605<\/span> <strong><span style=\"color: #000000;\">Middels<\/span><\/strong><\/span><\/p><p><span style=\"color: #ff9900;\">\u2605\u2605\u2605\u2605 <span style=\"color: #000000;\">Vanskelig<\/span><\/span><\/p><p><span style=\"color: #ff9900;\">\u2605\u2605\u2605\u2605\u2605 <span style=\"color: #000000;\">Sv\u00e6rt vanskelig<\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-a717060 elementor-widget elementor-widget-image\" data-id=\"a717060\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/11\/tour-100-km-2-a-3-jours-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"Itin\u00e9raire chiens de traineaux\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTczODAsInVybCI6Imh0dHBzOlwvXC93d3cuZXNjYXBhZGUtbm9ydmVnaWVubmUuY29tXC93cC1jb250ZW50XC91cGxvYWRzXC8yMDIzXC8xMVwvdG91ci0xMDAta20tMi1hLTMtam91cnMtc2NhbGVkLmpwZyJ9\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"753\" height=\"1024\" src=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/11\/tour-100-km-2-a-3-jours-753x1024.jpg\" class=\"attachment-large size-large wp-image-17380\" alt=\"\" srcset=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/11\/tour-100-km-2-a-3-jours-753x1024.jpg 753w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/11\/tour-100-km-2-a-3-jours-221x300.jpg 221w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/11\/tour-100-km-2-a-3-jours-768x1044.jpg 768w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/11\/tour-100-km-2-a-3-jours-1130x1536.jpg 1130w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/11\/tour-100-km-2-a-3-jours-1506x2048.jpg 1506w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/11\/tour-100-km-2-a-3-jours-scaled.jpg 1883w\" sizes=\"(max-width: 753px) 100vw, 753px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-182e134d elementor-widget elementor-widget-tp-button\" data-id=\"182e134d\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"tp-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pt-plus-button-wrapper   text-right   \"><div class=\"button_parallax   \" ><div id=\"button6a04bc82b6e0b\"  class=\" text-right ts-button content_hover_effect   \" ><div class=\"pt_plus_button btn6a04bc82b69ae button-style-1   \"  ><div class=\"animted-content-inner \"><a href=\"#\" target=\"_blank\" class=\"button-link-wrap \" role=\"button\" data-hover=\"Last ned filen i .pdf-format\"  >Last ned filen i .pdf-format<span class=\"btn-icon button-after\"><i aria-hidden=\"true\" class=\"icon icon-right-arrow1\"><\/i><\/span><div class=\"button_line\"><\/div><\/a><\/div><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62d6962d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62d6962d\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-16e88c2d\" data-id=\"16e88c2d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6463f34f elementor-tabs-view-horizontal elementor-widget elementor-widget-tabs\" data-id=\"6463f34f\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1681\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1681\" aria-expanded=\"false\">reisejournal<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1682\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1682\" aria-expanded=\"false\">Budsjettet<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1683\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1683\" aria-expanded=\"false\">alternativer<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1681\" aria-expanded=\"false\">reisejournal<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1681\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1681\" tabindex=\"0\" hidden=\"false\"><h3>DAG 1:<\/h3>\n<p class=\"p1\">Ankomst og innkvartering. Omvisning p\u00e5 g\u00e5rden og kennelen.<\/p>\n<h3 class=\"p1\">DAG 2:<\/h3>\n<p class=\"p1\">\u00abMushing-kurs\u00bb. F\u00f8rste kontakt med sleden.<\/p>\n<h3>DAG 3:<\/h3>\n<p class=\"p1\">Stell av hundene og forberedelse av utstyr \/ Briefing og selen av hundene \/ Dagslang hundeslederaid.<\/p>\n<h3>DAG 4:<\/h3>\nStell av hundene \/ Spadag, nordisk bad \/ badstue \/ avslapning\n<h3>DAG 5:<\/h3>\nHundeslede raid \/ Overnatting i hytte.\n<h3>DAG 6:<\/h3>\nHundeslede raid \/ <span style=\"color: #000000;\">Overnatting eller retur til basen avhengig av gruppens form.<\/span>\n<h3>DAG 7:<\/h3>\nRetur fra raid \/ Bes\u00f8k i R\u00f8ros eller aktiviteter etter eget valg.\n<h3>DAG 8:<\/h3>\n<span style=\"color: #000000;\">Avreise fra lodgen for retur til hjemmet ditt.<\/span>\n<h3 class=\"p1\">VIKTIG:<\/h3>\n<p class=\"p1\"><em><strong>Dette er et typisk program som kan endres basert p\u00e5 v\u00e6rmeldinger, spesielle forhold, \u00f8nsker og m\u00e5l for gruppen. Datoer for avreise\/ankomst kan justeres etter tilgjengelighet.<\/strong><\/em><\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1682\" aria-expanded=\"false\">Budsjettet<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1682\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1682\" tabindex=\"0\" hidden=\"hidden\"><strong><span style=\"color: #e2001a;\">PRISEN INKLUDERER<\/span><\/strong>\n<ul>\n \t<li>Overnatting p\u00e5 g\u00e5rden, basert p\u00e5 to personer per rom.<\/li>\n \t<li>Full pensjon under oppholdet fra dag 1 til 8\n<ul>\n \t<li>Frokost<\/li>\n \t<li><span style=\"color: #000000;\">Lunsjpakke<\/span><\/li>\n \t<li>Middag p\u00e5 g\u00e5rden<\/li>\n<\/ul>\n<\/li>\n \t<li><span style=\"color: #000000;\">L\u00e5n av utstyr p\u00e5 foresp\u00f8rsel (kuldesko \/ kjeledress \/ hansker)<\/span><\/li>\n \t<li><span style=\"color: #000000;\">Veiledning og assistanse fra St\u00e9phanie eller Jean-Philippe<\/span><\/li>\n \t<li>To badstuer per uke<\/li>\n<\/ul>\n<strong><span style=\"color: #e2001a;\">PRISEN INKLUDERER IKKE<\/span><\/strong>\n<ul>\n \t<li>Transport.<\/li>\n \t<li>Alkoholholdige drikker eller andre drikker<\/li>\n \t<li>Tips til guider og personlige utgifter.<\/li>\n \t<li>Avbestillingsforsikring, assistanse, hjemtransport og bagasjeforsikring<\/li>\n<\/ul>\n<em><strong>Alt som ikke er nevnt under \u00ab Prisen inkluderer \u00bb.<\/strong><\/em><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1683\" aria-expanded=\"false\">alternativer<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1683\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1683\" tabindex=\"0\" hidden=\"hidden\"><ul>\n \t<li>Forleng reisen din p\u00e5 foresp\u00f8rsel, avhengig av eksisterende reservasjoner i perioden.<\/li>\n \t<li>Enkeltrom p\u00e5 g\u00e5rden etter foresp\u00f8rsel.<\/li>\n \t<li>\u00d8nsker du en statlig sertifisert guide til \u00e5 f\u00f8lge deg i l\u00f8pet av uken (6 dager)\n<ul>\n \t<li>(280\u20ac \/ dag \/ person &#8211; basert p\u00e5 4 personer &#8211; forbeholdt tilgjengelighet)<\/li>\n<\/ul>\n<\/li>\n \t<li>Leiebil p\u00e5 stedet hvis du kommer med tog til Tolga.<\/li>\n \t<li><strong><a href=\"mailto:contact@escapade-norvegienne.com\">For andre foresp\u00f8rsel, vennligst kontakt oss.<\/a><\/strong><\/li>\n<\/ul><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4b5df4ea\" data-id=\"4b5df4ea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e406520 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7e406520\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/a-komme-seg-til-hodalen\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Hvordan komme seg til Hodalen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6028d21e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6028d21e\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/overnatting\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">overnattingsl\u00f8sning<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4bae2936 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4bae2936\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/aktiviteter-tilbudt-av-escapade\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Tilpass din aktivitet<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-300f80b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"300f80b\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4febe3e\" data-id=\"4febe3e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c5e82c elementor-widget elementor-widget-elementskit-heading\" data-id=\"5c5e82c\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-text_left   ekit_heading_mobile- ekit-heading__title-in-left\">\t\t\t\t<span class='ekit-heading__shadow-text'>\n\t\t\t\t\tRammen\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<div class='ekit-heading__title-wrapper'>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='ekit-heading__content-wrapper'>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9456f9 text-left elementor-widget elementor-widget-tp-adv-text-block\" data-id=\"c9456f9\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"tp-adv-text-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pt-plus-text-block-wrapper\" ><div class=\"text_block_parallax\"><div class=\"pt_plus_adv_text_block \" ><div class=\"text-content-block\"><p class=\"p1\"><strong>St\u00e9phanie og Jean Philippe<\/strong> \u00f8nsker deg velkommen midt i hjertet av Norge p\u00e5 en gammel, renovert t\u00f8mmerg\u00e5rd. Hytter og gjesterom st\u00e5r til din disposisjon for overnatting, og spisestuen i ubehandlet tre gir en varm og koselig atmosf\u00e6re ved peisen, perfekt for \u00e5 nyte deilige pauser midt p\u00e5 vinteren. Hedmark-regionen, en innlandsprovins i Norge, er kjent for sine ideelle sn\u00f8forhold, ekstreme temperaturer, lokale matvarer, tradisjonelle t\u00f8mmerhus og sine ville, avsidesliggende fjellandskap. Utforsk naturen og opplev eventyret i den store kulden gjennom fjellaktiviteter som nordisk ski, topptur, truger, hundesledekj\u00f8ring, isfiske, nordisk bad og badstue med vedfyring, naturopplevelser, fototurer ...<\/p>\n<p class=\"p1\"><em><strong>Samtidig som du drar nytte av v\u00e5r kunnskap om regionen og v\u00e5r erfaring i en varm atmosf\u00e6re der vi gir deg den beste velkomsten.<\/strong><\/em><\/p><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-601786d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"601786d\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2483321\" data-id=\"2483321\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8fead79 elementor-widget elementor-widget-image\" data-id=\"8fead79\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"868\" src=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/chien-traineau-944x1024.png\" class=\"attachment-large size-large wp-image-16609\" alt=\"\" srcset=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/chien-traineau-944x1024.png 944w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/chien-traineau-277x300.png 277w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/chien-traineau-768x833.png 768w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/chien-traineau.png 1087w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1d2cc36 elementor-widget elementor-widget-spacer\" data-id=\"1d2cc36\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-99f6101\" data-id=\"99f6101\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71d5c76 elementor-widget elementor-widget-elementskit-heading\" data-id=\"71d5c76\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-text_left   ekit_heading_mobile- ekit-heading__title-in-left\">\t\t\t\t<span class='ekit-heading__shadow-text'>\n\t\t\t\t\tProgrammet\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<div class='ekit-heading__title-wrapper'>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='ekit-heading__content-wrapper'>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06e6b05 elementor-widget elementor-widget-text-editor\" data-id=\"06e6b05\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><strong>Eventyruke i Grand Nord:<\/strong><\/p>\n<p class=\"p2\">Alt inkludert opphold med full pensjon og aktiviteter som inkluderer en halv dags introduksjon til hundekj\u00f8ring med Jean Philippe, en heldagstur med hundeslede (som passasjer i sleden eller som f\u00f8rer, avhengig av ditt \u00f8nske og musherens vurdering), et to-dagers raid med hundeslede og overnatting i hytte i naturen med hundene, spadag med vedfyrt nordisk bad og tilgang til badstuen. Vi legger stor vekt p\u00e5 m\u00e5ltidene, som kombinerer lokal gastronomi og fransk tradisjon med ett enkelt m\u00e5l: \u00e5 glede og tilfredsstille deg.<\/p>\n<p class=\"p2\">Omvisning i kennelen og stell av hundene er tilgjengelig hver dag. Innholdet i oppholdet kan tilpasses v\u00e6rforholdene og dine \u00f8nsker.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-532a0f8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"532a0f8\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0d651bb\" data-id=\"0d651bb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-177126d elementor-widget elementor-widget-elementskit-heading\" data-id=\"177126d\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-text_left   ekit_heading_mobile- ekit-heading__title-in-left\">\t\t\t\t<span class='ekit-heading__shadow-text'>\n\t\t\t\t\tHundesledekj\u00f8ring\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<div class='ekit-heading__title-wrapper'>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='ekit-heading__content-wrapper'>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c533520 elementor-widget elementor-widget-heading\" data-id=\"c533520\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">V\u00e5r filosofi: deltakende oppdagelse<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8ef10d2 elementor-widget elementor-widget-text-editor\" data-id=\"8ef10d2\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hundene deler v\u00e5rt liv, og kennelen er perfekt integrert p\u00e5 g\u00e5rden. Som gjester vil dere bli involvert i ulike daglige oppgaver som stell av hundene, f\u00f4ring, rengj\u00f8ring av kennelen osv. Disse oppgavene bidrar til \u00e5 skape b\u00e5ndet mellom musheren og hundene, og dette b\u00e5ndet vil v\u00e6re sv\u00e6rt viktig n\u00e5r du skal kj\u00f8re sleden.<\/p><p>Under den halve dagen med oppl\u00e6ring vil du l\u00e6re det grunnleggende om livet som musher: det daglige arbeidet, stell, utstyr, hvordan sette p\u00e5 og ta av en sele, st\u00f8vler, jakker, sele for hundene, sleden, styring og mange tips som Jean Philippe vil dele, frukten av mange \u00e5rs lidenskap og erfaring med sine hunder og sporten.<\/p><p>Under flere dagers raid eller utflukter vil du ogs\u00e5 bli involvert i ulike oppgaver knyttet til livet i fjellet med hunder. Jean Philippe leder raidene og fordeler oppgavene: sette opp leiren, hente vann, lage b\u00e5l, tilberede m\u00e5ltider osv. M\u00e5let er at hele gruppen skal s\u00f8rge for trivselen til b\u00e5de hundene og menneskene, slik at raidet blir en uforglemmelig opplevelse. Du er en aktiv deltaker i eventyret, ikke bare en enkel tilskuer.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef167b9 elementor-widget elementor-widget-heading\" data-id=\"ef167b9\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ditt skreddersydde opphold:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a2760d elementor-widget elementor-widget-text-editor\" data-id=\"6a2760d\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Oppholdene \u00abEventyr i Grand Nord\u00bb er rettet mot et publikum som s\u00f8ker unike opplevelser og eventyr. De krever utmerket fysisk form, eventuell beherskelse av vintersport og forberedelse p\u00e5 fysisk innsats som kan v\u00e6re betydelig avhengig av forholdene man m\u00f8ter.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2df6ab elementor-widget elementor-widget-elementskit-heading\" data-id=\"b2df6ab\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-text_left   ekit_heading_mobile- ekit-heading__title-in-left\">\t\t\t\t<span class='ekit-heading__shadow-text'>\n\t\t\t\t\tVilk\u00e5rene\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<div class='ekit-heading__title-wrapper'>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class='ekit-heading__content-wrapper'>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27c1784 elementor-widget elementor-widget-heading\" data-id=\"27c1784\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Fysisk form:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aec1f34 elementor-widget elementor-widget-text-editor\" data-id=\"aec1f34\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Aktiviteter og hundesledekj\u00f8ring krever god fysisk form. Deltakelse i slederaider vil derfor bli vurdert av Jean Philippe for \u00e5 unng\u00e5 \u00e5 belaste gruppen. Vi anbefaler \u00e5 tegne en spesifikk forsikring og \u00e5 f\u00e5 en positiv vurdering fra legen din.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08aa98c elementor-widget elementor-widget-heading\" data-id=\"08aa98c\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">N\u00f8dvendig utstyr:<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a94753 elementor-widget elementor-widget-text-editor\" data-id=\"2a94753\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Du m\u00e5 v\u00e6re utstyrt med kl\u00e6r og sko som er tilpasset kulde, samt eventuelt en sovepose for netter i hytte. En badedrakt anbefales for spadagen\/nordisk bad. Vi s\u00f8rger for senget\u00f8y og h\u00e5ndkl\u00e6r. Vi har ogs\u00e5 kuldekjeledresser og -sko som du kan l\u00e5ne ved behov (vennligst oppgi st\u00f8rrelsen din).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e264434 elementor-widget elementor-widget-heading\" data-id=\"e264434\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Anbefalinger :<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-016fb03 elementor-widget elementor-widget-text-editor\" data-id=\"016fb03\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\">Temperaturene kan v\u00e6re ekstremt kalde. For at du skal kunne nyte opplevelsen under best mulige forhold, anbefaler vi f\u00f8lgende utstyr (eller tilsvarende):<\/p>\n<p class=\"p1\"><strong>&#8211;<\/strong> Skibriller \/ skimaske (sv\u00e6rt nyttig i d\u00e5rlig v\u00e6r)<\/p>\n<p class=\"p1\"><strong>&#8211;<\/strong> Skihansker: 2 par<\/p>\n<p class=\"p1\"><strong>&#8211;<\/strong> Ekstra kl\u00e6r og undert\u00f8y (type Damard\u00ae). (<strong>NB:<\/strong> det er mulig \u00e5 kj\u00f8pe ullundert\u00f8y (langermet T-skjorte + tights) p\u00e5 stedet, som er sv\u00e6rt vanlig i Norge og gir utmerket kvalitet til prisen)<\/p>\n<p class=\"p1\"><strong>&#8211;<\/strong> Hodelykt 170 lumen type Led Lenser\u00ae H7<\/p>\n<p class=\"p1\"><strong>&#8211;<\/strong> Vanntette gamasjer for \u00e5 g\u00e5 i sn\u00f8en<\/p>\n<p class=\"p1\">Eventuelt: Kuldebestandige sko av typen \u00abSOREL\u00bb\u00ae (bruk ned til -30\u00b0C) og sovepose med komfort p\u00e5 rundt -15\u00b0C (for eventuell overnatting ute) eller et soveposelaken av typen \u00absilke\u00bb.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b16b8a6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b16b8a6\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6502018\" data-id=\"6502018\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-811fd49 elementor-widget elementor-widget-elementskit-gallery\" data-id=\"811fd49\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_gallery_columns&quot;:&quot;3&quot;,&quot;ekit_gallery_columns_tablet&quot;:&quot;2&quot;,&quot;ekit_gallery_columns_mobile&quot;:&quot;1&quot;,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >                        <div class=\"ekit_gallery_grid_wraper\"><div id=\"ekit_gallery_811fd49\" class=\"ekit_gallery_grid\" data-tilt-config=\"{&quot;disableAxis&quot;:null,&quot;easing&quot;:&quot;cubic-bezier(.03, .98, .52, .99)&quot;,&quot;glare&quot;:false,&quot;transition&quot;:true}\" data-masonry-config=\"{&quot;itemSelector&quot;:&quot;.ekit_gallery_grid_item&quot;}\">                \t\t\t\t\t\t\t<div class=\"ekit_gallery_grid_item ekit_gallery__filter- gallery_grid_style\">\n\t\t\t\t\t\t\t\t<div class=\"elementskit-single-portfolio-item \"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t<div class=\"elementskit-portfolio-thumb\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"padding-bottom: calc(1.4 * 100%)\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"elementskit-grid__img\" src=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/05\/slide-07.jpg\" alt=\"gallery grid image\"\/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementskit-hover-area\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-hover-content ekit_vertical_alignment_center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div><!-- .elementskit-hover-area END -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ekit-gallery-image-overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .elementskit-single-portfolio-item END -->\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ekit_gallery_grid_item ekit_gallery__filter- gallery_grid_style\">\n\t\t\t\t\t\t\t\t<div class=\"elementskit-single-portfolio-item \"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t<div class=\"elementskit-portfolio-thumb\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"padding-bottom: calc(1.4 * 100%)\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"elementskit-grid__img\" src=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/04\/hiver-1.jpg\" alt=\"gallery grid image\"\/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementskit-hover-area\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-hover-content ekit_vertical_alignment_center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div><!-- .elementskit-hover-area END -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ekit-gallery-image-overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .elementskit-single-portfolio-item END -->\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ekit_gallery_grid_item ekit_gallery__filter- gallery_grid_style\">\n\t\t\t\t\t\t\t\t<div class=\"elementskit-single-portfolio-item \"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t<div class=\"elementskit-portfolio-thumb\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"padding-bottom: calc(1.4 * 100%)\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"elementskit-grid__img\" src=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/04\/IMG_4883.jpeg\" alt=\"gallery grid image\"\/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementskit-hover-area\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-hover-content ekit_vertical_alignment_center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div><!-- .elementskit-hover-area END -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ekit-gallery-image-overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .elementskit-single-portfolio-item END -->\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ekit_gallery_grid_item ekit_gallery__filter- gallery_grid_style\">\n\t\t\t\t\t\t\t\t<div class=\"elementskit-single-portfolio-item \"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t<div class=\"elementskit-portfolio-thumb\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"padding-bottom: calc(1.4 * 100%)\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"elementskit-grid__img\" src=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/01\/DJI_0371-scaled-1.jpg\" alt=\"gallery grid image\"\/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementskit-hover-area\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-hover-content ekit_vertical_alignment_center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div><!-- .elementskit-hover-area END -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ekit-gallery-image-overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .elementskit-single-portfolio-item END -->\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ekit_gallery_grid_item ekit_gallery__filter- gallery_grid_style\">\n\t\t\t\t\t\t\t\t<div class=\"elementskit-single-portfolio-item \"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t<div class=\"elementskit-portfolio-thumb\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"padding-bottom: calc(1.4 * 100%)\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"elementskit-grid__img\" src=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/01\/P7010492-scaled-1.jpg\" alt=\"gallery grid image\"\/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementskit-hover-area\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-hover-content ekit_vertical_alignment_center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div><!-- .elementskit-hover-area END -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ekit-gallery-image-overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .elementskit-single-portfolio-item END -->\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ekit_gallery_grid_item ekit_gallery__filter- gallery_grid_style\">\n\t\t\t\t\t\t\t\t<div class=\"elementskit-single-portfolio-item \"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t<div class=\"elementskit-portfolio-thumb\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\tstyle=\"padding-bottom: calc(1.4 * 100%)\"\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"elementskit-grid__img\" src=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/01\/IMG_1458-scaled-1.jpg\" alt=\"gallery grid image\"\/>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementskit-hover-area\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementskit-hover-content ekit_vertical_alignment_center\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div><!-- .elementskit-hover-area END -->\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"ekit-gallery-image-overlay\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><!-- .elementskit-single-portfolio-item END -->\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f0b0f67\" data-id=\"f0b0f67\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd9a4fa elementor-widget elementor-widget-heading\" data-id=\"fd9a4fa\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">informasjonsforesp\u00f8rsel<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-247024f elementor-widget elementor-widget-text-editor\" data-id=\"247024f\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Alle felt merket med en stjerne (*) er obligatoriske<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d72036a elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"d72036a\" data-element_type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Suivant&quot;,&quot;step_previous_label&quot;:&quot;Pr\\u00e9c\\u00e9dent&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Nouveau formulaire\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"24506\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"d72036a\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Escapade Norvegienne\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Navn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_576bc9a elementor-col-50\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_576bc9a]\" id=\"form-field-field_576bc9a\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"Fornavn\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"E-post\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-hulk_epfitf_telephone elementor-field-group elementor-column elementor-field-group-field_c4ff312 elementor-col-50 elementor-field-required\">\n\t\t\t\t\t<div\n\tclass=\"hulk_epfitf_telephone_wrap elementor-repeater-item-c4ff312\"\n\tdata-settings='{\"_id\":\"c4ff312\",\"id\":\"form-field-field_c4ff312\",\"custom_id\":\"field_c4ff312\",\"name\":\"form_fields[field_c4ff312]\",\"class\":\"elementor-field elementor-size-sm elementor-field-textual\",\"value\":\"\",\"required\":true,\"placeholder\":\"Telefon\",\"initialCountry\":\"no\",\"onlyCountries\":[],\"excludeCountries\":[],\"countryOrder\":[],\"nationalMode\":true,\"strictMode\":true,\"enableValidation\":true}'\n\tdata-id=\"c4ff312\"\n>\n\t<input\n\t\ttype=\"text\"\n\t\taria-label=\"international telephone number\"\n\t\tid=\"form-field-field_c4ff312\"\n\t\tname=\"form_fields[field_c4ff312]\"\n\t\tclass=\"elementor-field elementor-size-sm  elementor-field-textual\"\n\t\tvalue=\"\"\n\t\tplaceholder=\"Telefon\"\n\t>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-date elementor-field-group elementor-column elementor-field-group-field_66f157e elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\n\t\t<input type=\"date\" name=\"form_fields[field_66f157e]\" id=\"form-field-field_66f157e\" class=\"elementor-field elementor-size-sm  elementor-field-textual elementor-date-field\" placeholder=\"Ankomstdato\" required=\"required\" pattern=\"[0-9]{4}-[0-9]{2}-[0-9]{2}\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-date elementor-field-group elementor-column elementor-field-group-field_9bc1087 elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\n\t\t<input type=\"date\" name=\"form_fields[field_9bc1087]\" id=\"form-field-field_9bc1087\" class=\"elementor-field elementor-size-sm  elementor-field-textual elementor-date-field\" placeholder=\"Avreisedato\" required=\"required\" pattern=\"[0-9]{4}-[0-9]{2}-[0-9]{2}\">\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"Din foresp\u00f8rsel\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-acceptance elementor-field-group elementor-column elementor-field-group-field_6ada6bd elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"elementor-field-subgroup\">\n\t\t\t<span class=\"elementor-field-option\">\n\t\t\t\t<input type=\"checkbox\" name=\"form_fields[field_6ada6bd]\" id=\"form-field-field_6ada6bd\" class=\"elementor-field elementor-size-sm  elementor-acceptance-field\">\n\t\t\t\t<label for=\"form-field-field_6ada6bd\">Ved \u00e5 merke av i denne boksen og sende inn dette skjemaet, godtar jeg at mine personopplysninger brukes til \u00e5 kontakte meg i forbindelse med foresp\u00f8rselen min angitt i dette skjemaet. Ingen annen behandling vil bli utf\u00f8rt med informasjonen min. Se v\u00e5r <a href=\"\/personvernregler\/\">personvernerkl\u00e6ring.<\/a><\/label>\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-sm\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Sende<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31513d7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"31513d7\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8277d2d\" data-id=\"8277d2d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8958dc7 text-left elementor-widget elementor-widget-tp-adv-text-block\" data-id=\"8958dc7\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"tp-adv-text-block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"pt-plus-text-block-wrapper\" ><div class=\"text_block_parallax\"><div class=\"pt_plus_adv_text_block \" ><div class=\"text-content-block\"><p>Ved etablert risikosituasjon eller ugunstige v\u00e6rforhold forbeholder vi oss retten til \u00e5 iverksette ulike tiltak, for eksempel \u00e5 styrke veiledningen for guidede turer, justere rutene for v\u00e5re turer, eller midlertidig suspendere en tur eller et opphold hvis vi anser risikoniv\u00e5et som uakseptabelt.<\/p><p>V\u00e5rt viktigste engasjement er din sikkerhet og din fulle tilfredshet.<\/p><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-350ca1a9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"350ca1a9\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1f14f8f8\" data-id=\"1f14f8f8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ea0520 test elementor-widget elementor-widget-elementskit-heading\" data-id=\"7ea0520\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_center   ekit_heading_tablet-   ekit_heading_mobile-\">\t\t\t\t<span class='ekit-heading__shadow-text'>\n\t\t\t\t\tEventyr i Grand Nord\t\t\t\t<\/span>\n\t\t\t<h2 class=\"ekit-heading--title elementskit-section-title \">tilbakemeldinger fra <span><span>kunder<\/span><\/span><\/h2>\t\t\t\t<div class='ekit-heading__description'>\n\t\t\t\t\t<p>Kundene som har satt pris p\u00e5 dette oppholdet: Eventyr i Grand Nord<\/p>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7352580a elementor-widget elementor-widget-shortcode\" data-id=\"7352580a\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><pre class=\"ti-widget\"><template id=\"trustindex-google-widget-html\"><div class=\" ti-widget  ti-goog ti-review-text-mode-readmore ti-text-align-left\" data-no-translation=\"true\" data-time-locale=\"il y a %d %s|aujourd'hui|jour|jours|semaine|semaines|mois|mois|ann\u00e9e|ans\" data-layout-id=\"13\" data-layout-category=\"slider\" data-set-id=\"ligth-border\" data-pid=\"\" data-language=\"fr\" data-close-locale=\"Fermer\" data-review-target-width=\"275\" data-css-version=\"2\" data-reply-by-locale=\"R\u00e9ponse du propri\u00e9taire\" data-pager-autoplay-timeout=\"6\"> <div class=\"ti-widget-container ti-col-4\"> <div class=\"ti-footer source-Google\"> <div class=\"ti-row\"> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh5.googleusercontent.com\/-nJqW9Csg9jI\/AAAAAAAAAAI\/AAAAAAAAAAA\/hxSn8yA0AvI\/s160-p-k-no-ns-nd\/photo.jpg\" alt=\"Escapade Norv\u00e9gienne\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Escapade Norv\u00e9gienne<\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-rating-text\"> <span class=\"nowrap\"><strong>29 avis Google<\/strong><\/span> <\/div> <div class=\"ti-header-write-btn-container\"> <a href=\"https:\/\/admin.trustindex.io\/api\/googleWriteReview?place-id=ChIJZ5g2obCAa0YR5qpydYB8Twc\" class=\"ti-header-write-btn\" role=\"button\" aria-label=\"\u00c9crire un avis sur Google\" target=\"_blank\" rel=\"noopener nofollow\">\u00c9crire un avis<\/a> <\/div>  <\/div> <\/div> <\/div> <div class=\"ti-reviews-container\"> <div class=\"ti-controls\"> <div class=\"ti-next\" aria-label=\"Avis suivante\" role=\"button\"><\/div> <div class=\"ti-prev\" aria-label=\"Avis pr\u00e9c\u00e9dent\" role=\"button\"><\/div> <\/div> <div class=\"ti-reviews-container-wrapper\">  <div data-empty=\"0\" data-time=\"1749600000\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLnxEF77g34ADjol8h95X1k-iBwWy1tWvgMDhzZTV9qeTjMTA=w40-h40-c-rp-mo-br100\" alt=\"Fran\u00e7ois de Cazenove profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Fran\u00e7ois de Cazenove <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Superbe s\u00e9jour de p\u00eache - pour la 2\u00b0fois.\nAccueil tr\u00e8s sympa, guidage complet et pr\u00e9cis, gastronomie parfaite, bref super s\u00e9jour<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1725321600\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKZfmeIZn2l-c3tmm7NrJcMN0WR3m_3s8GFnEetYIdNo8zV6A=w40-h40-c-rp-mo-br100\" alt=\"Jean-Yves R profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Jean-Yves R <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Gentillesse et bonne humeur sont les mots clefs de ce s\u00e9jour chez Jean-Philippe et sa famille. Entre superbes d\u00e9couvertes, lieux sauvages, gastronomie, toute la famille participe pour vous laisser un souvenir m\u00e9morable de s\u00e9jour. Cano\u00eb, atelier de montage de mouches, \u00e9tang secret pour p\u00eacher le brochet en surface, Jean-Philippe a toujours \u00e9t\u00e9 \u00e0 notre \u00e9coute pour nous proposer une riche exp\u00e9rience! Merci et \u00e0 bient\u00f4t!!!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1720051200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocLC6Wafqn93T8bnNeCmDj_DOck1oXQNjg-YFD5_WEyZAM8Okw=w40-h40-c-rp-mo-ba2-br100\" alt=\"Jeremy Monini profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Jeremy Monini <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Superbe s\u00e9jour merci \u00e0 vous tous !\nPress\u00e9 de revenir !<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1720051200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKF3bECbCKoNwY6yca9BxBCxbNhxz7tVT9_RRl9szXF8VEYNg=w40-h40-c-rp-mo-br100\" alt=\"Steph Warfou profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Steph Warfou <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->An unforgettable stay for flyfishing.\nThe welcome of the owners is warm and helpful.\nThe comfort of the traditional lodge is highly sufficient for June long days of fishing.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1719705600\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKH-vzNfV6FxrztXu94tzM0oINpKkGC_4USIqG6bvgnFOgV2w=w40-h40-c-rp-mo-br100\" alt=\"Jean-Luc RETTEL profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Jean-Luc RETTEL <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Jean Philippe n economise pas son temps pour faire d\u00e9couvrir ses coins de p\u00eache dans une nature magnifique.  St\u00e9phanie pr\u00e9pare chaque soir un d\u00eener gastronomique.  Une semaine de pure d\u00e9tente.  Merci pour la gentillesse de votre accueil sans oublier Sophie<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1714867200\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjWhjE5DnEoQoVA9W36M6up7I0OUdSjid3zN6rSPCnAvnKd5tMzI=w40-h40-c-rp-mo-br100\" alt=\"Florian Lagleize profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Florian Lagleize <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->S\u00e9jour magnifique chez Jean-Philippe, St\u00e9phanie... et Sophie !\n\nUn lieu magique avec les lacs gel\u00e9s, un accueil super chaleureux et des activit\u00e9s magiques (chiens de traineaux, ice fishing, rando, barbecues etc...).\n\nNous avons profit\u00e9 \u00e0 fond en famille.\n\nPlus que des vacances : une experiencz dont on se rappellera longtemps !\n\nMerci encore pour l'accueil.\nFlorian<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1713744000\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjW57Sg4-l_fcdZ_vNc85Vy_cuEg4VctOd4TyvwMbsms1Xzhs6Rd=w40-h40-c-rp-mo-ba5-br100\" alt=\"Antons Kija\u0146ica profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Antons Kija\u0146ica <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Great old-time cottage farm house located in a mountainous region. Outstanding views are an obvious consequence, but the main reason we rented the house was for its cozy old-timey atmosphere. There's no running water or gas inside the house, the toilet and shower is outside the house (there is running water there), and the heating is done via an electric stove, so if you're looking for a place to shut off from the world, this is it. It feels very beginning of the 20th century inside, and aside from a few modern touches here and there, you'll feel yourself at your grandma's farm house.\nStefanie is an awesome host, we loved the breakfast (it was maybe a bit too stuffy, but that's 100% on us \ud83d\ude04) and the overall experience will definitely leave a lasting memory. Hope to visit again!\n\nAr m\u012blest\u012bbu, Antons un Anastasija no Latvijas!<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1713744000\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjVG76rKWdWkvlu0r8PYE6sQ6YZPCvis6YBru-N1cz9fJLCwPru1aw=w40-h40-c-rp-mo-ba4-br100\" alt=\"An Ki profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> An Ki <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->A very cozy place that took me back to my childhood visits to my grandmother's farm. Beautiful location, incredibly delicious breakfast, and a fantastic atmosphere.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1705536000\" class=\"ti-review-item source-Google ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a-\/ALV-UjUKYknlIF6T4uAfQG1du6fOmY2sJCWS2hUzH_4xvO0nDxyAijk=w40-h40-c-rp-mo-br100\" alt=\"M\u00e9lanie Barreau profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> M\u00e9lanie Barreau <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Google\/star\/f.svg\" alt=\"Google\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review ti-verified-platform\"><span class=\"ti-verified-tooltip\">Trustindex v\u00e9rifie que la source originale de l'avis est Google.<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT -->Une exp\u00e9rience hors du commun aux c\u00f4t\u00e9s de Jean-Philippe et St\u00e9phanie pour ces premiers jours de 2024, une impression de bout du monde dans la chaleur de leur maison et de leur accueil.\nUne exp\u00e9rience privil\u00e9gi\u00e9e de d\u00e9couverte de traineau \u00e0 chiens. Merci \u00e0 vous<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <\/div> <div class=\"ti-controls-line\"> <div class=\"dot\"><\/div> <\/div>   <\/div> <\/div> <\/div> <\/template><\/pre><div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?wp-widget\" data-template-id=\"trustindex-google-widget-html\" data-css-url=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/trustindex-google-widget.css?1765976255\"><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-151bda0a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"151bda0a\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-60cac549\" data-id=\"60cac549\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-134e96dc elementor-widget elementor-widget-shortcode\" data-id=\"134e96dc\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><pre class=\"ti-widget\"><template id=\"trustindex-booking-widget-html\"><div class=\" ti-widget  ti-book ti-review-text-mode-readmore ti-text-align-left\" data-no-translation=\"true\" data-time-locale=\"il y a %d %s|aujourd'hui|jour|jours|semaine|semaines|mois|mois|ann\u00e9e|ans\" data-layout-id=\"5\" data-layout-category=\"slider\" data-set-id=\"ligth-border\" data-pid=\"\" data-language=\"fr\" data-close-locale=\"Fermer\" data-review-target-width=\"275\" data-css-version=\"2\" data-reply-by-locale=\"R\u00e9ponse du propri\u00e9taire\" data-pager-autoplay-timeout=\"6\"> <div class=\"ti-widget-container ti-col-4\"> <div class=\"ti-footer ti-footer-grid source-Booking\"> <div class=\"ti-fade-container\"> <div class=\"ti-rating-text\"> <strong class=\"ti-rating ti-rating-large\"> EXCELLENT <\/strong> <\/div> <span class=\"ti-stars star-lg\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/e.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><\/span> <div class=\"ti-rating-text\"> <span class=\"nowrap\">Bas\u00e9e sur <strong>23 avis<\/strong><\/span> <\/div> <div class=\"ti-large-logo\"> <div class=\"ti-v-center\"> <trustindex-image class=\"ti-logo-fb\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/logo.svg\" width=\"150\" height=\"25\" loading=\"lazy\" alt=\"Booking\"><\/trustindex-image> <\/div> <\/div> <\/div> <\/div> <div class=\"ti-reviews-container\"> <div class=\"ti-controls\"> <div class=\"ti-next\" aria-label=\"Avis suivante\" role=\"button\"><\/div> <div class=\"ti-prev\" aria-label=\"Avis pr\u00e9c\u00e9dent\" role=\"button\"><\/div> <\/div> <div class=\"ti-reviews-container-wrapper\">  <div data-empty=\"0\" data-time=\"1744329600\" class=\"ti-review-item source-Booking ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh4.googleusercontent.com\/-lldLH3eZeQI\/AAAAAAAAAAI\/AAAAAAAAAOg\/8oK7w_ud-oA\/s96-c\/photo.jpg\" alt=\"Torbj\u00f6rn profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Torbj\u00f6rn <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/e.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/e.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/e.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/e.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review\"><span class=\"ti-verified-tooltip\">v\u00e9rifi\u00e9<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT --><strong>Besviken<\/strong>\n\u263aN\u00e4ra fisket\n\n\u2639Inget k\u00f6k\nInget bord \u00e5 stolar p\u00e5 rummet<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1744156800\" class=\"ti-review-item source-Booking ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocI-rwrBFR9--fnMQSo1j2-wSubAl4JXvRuQ2k66OGg2v3Y=s96-c\" alt=\"Maarja profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Maarja <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/e.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review\"><span class=\"ti-verified-tooltip\">v\u00e9rifi\u00e9<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT --><strong>Very Good<\/strong><!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1744156800\" class=\"ti-review-item source-Booking ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/cf.bstatic.com\/static\/img\/review\/avatars\/ava-j\/f69a0f45af414641ac0371c1f139c49637969c6c.png\" alt=\"Jenyfer profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Jenyfer <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review\"><span class=\"ti-verified-tooltip\">v\u00e9rifi\u00e9<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT --><strong>D\u00e9connexion et authenticit\u00e9<\/strong>\n\u263aLa petite cabane de Stephanie et Jean-Philippe est tr\u00e8s authentique, tr\u00e8s confort, le po\u00eale chauffe super bien, et on a tout ce qu\u2019il faut pour cuisiner.\n Le calme et le silence font partie du d\u00e9cor en plus de la vue magnifique sur la toundra et les sommets qui entourent le lieu.\nJ\u2019\u00e9tais tr\u00e8s bien accueilli par Stephanie et Jean-Philippe .<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1743379200\" class=\"ti-review-item source-Booking ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/cf.bstatic.com\/static\/img\/review\/avatars\/ava-o\/ecc2e23c1dd875ae18fc261d4a08d35f71db9440.png\" alt=\"Olena profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Olena <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review\"><span class=\"ti-verified-tooltip\">v\u00e9rifi\u00e9<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT --><strong>Exceptional<\/strong><!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1733875200\" class=\"ti-review-item source-Booking ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/cf.bstatic.com\/static\/img\/review\/avatars\/ava-f\/8ecb6dbf787bac20deb3945d9c8a8b1c94cc5e64.png\" alt=\"Fredrik profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Fredrik <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/e.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review\"><span class=\"ti-verified-tooltip\">v\u00e9rifi\u00e9<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT --><strong>Was a great trip and good host!<\/strong>\n\u263a Very good places for kids, lots of space to play outside. Not too far away from R\u00f8ros.\n\n\u2639 You get what you pay for, so over all happy.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1726704000\" class=\"ti-review-item source-Booking ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/cf.bstatic.com\/static\/img\/review\/avatars\/ava-j\/f69a0f45af414641ac0371c1f139c49637969c6c.png\" alt=\"Jan profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Jan <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/e.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review\"><span class=\"ti-verified-tooltip\">v\u00e9rifi\u00e9<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT --><strong>Very Good<\/strong><!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1726444800\" class=\"ti-review-item source-Booking ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/cf.bstatic.com\/static\/img\/review\/avatars\/ava-j\/f69a0f45af414641ac0371c1f139c49637969c6c.png\" alt=\"Jonas profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Jonas <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review\"><span class=\"ti-verified-tooltip\">v\u00e9rifi\u00e9<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT --><strong>Excellent value for money. Cosy. Very nice staff. Highly recommended. Will surely come back again soon.<\/strong>\n\u263a Old style cabin. Cosy. Easy to park your car nearby. Everything you could possibly need inside, including powerbanks.\n\n\u2639 Would have appreciated a toilet\/outhouse near the cabin.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1726272000\" class=\"ti-review-item source-Booking ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/ACg8ocKdGyrhTX4kPXWiu3_cxbIV77jWIUUNPFShFjUxLKmHMujzrJWK=s96-c\" alt=\"Jon profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Jon <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review\"><span class=\"ti-verified-tooltip\">v\u00e9rifi\u00e9<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT --><strong>En skjult diamant.. Grip sjansen!<\/strong>\n\u263aBodde i en fantastisk liten t\u00f8mmerkoie, uten vann og str\u00f8m. Skulle egentlig dra videre etter en overnatting, men ble v\u00e6rfast i 2 ekstra d\u00f8gn. Kjempekoselig sted, et perfekt sted for avkobling. Koia var blant annet utstyrt med kj\u00f8kken, en liten peis og en herlig oljelampe som laget en nydelig atmosf\u00e6re! Bestilte i tillegg 3 retters middag 2 av dagene. Med vertinne Stephanie over grytene ble herlige retter servert med en kvalitet og anretning som kan m\u00e5le seg med restauranter i toppklasse! Rikholdig og deilig frokost, med hjemmebakt br\u00f8d og det hele. Vertskapet kan jeg ikke gi nok skryt og honn\u00f8r! Kjempehyggelige folk med stort hjerte.\n\n\u2639Her er det ingenting \u00e5 mislike.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1726099200\" class=\"ti-review-item source-Booking ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/cf.bstatic.com\/static\/img\/review\/avatars\/ava-r\/29d5c93ac6953138bfc6f214a4c5a0f8b712b57b.png\" alt=\"Rickard profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Rickard <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review\"><span class=\"ti-verified-tooltip\">v\u00e9rifi\u00e9<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT --><strong>Ett mysigt, trevlig boende och en god natts s\u00f6mn<\/strong>\n\u263aLugnet och stilen<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <div data-empty=\"0\" data-time=\"1724889600\" class=\"ti-review-item source-Booking ti-image-layout-thumbnail\" data-id=\"cfcd208495d565ef66e7dff9f98764da\"> <div class=\"ti-inner\"> <div class=\"ti-review-header\"> <div class=\"ti-platform-icon ti-with-tooltip\"> <span class=\"ti-tooltip\">Publi\u00e9 sur <\/span> <trustindex-image data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/icon.svg\" alt=\"\" width=\"20\" height=\"20\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-img\"> <trustindex-image data-imgurl=\"https:\/\/lh3.googleusercontent.com\/a\/AAcHTtetnt_y9ysyGQg1xbViEW4avsZXpLKwsIB9-PYB8ELFMg=s96-c\" alt=\"Koivunen profile picture\" loading=\"lazy\"><\/trustindex-image> <\/div> <div class=\"ti-profile-details\"> <div class=\"ti-name\"> Koivunen <\/div> <div class=\"ti-date\"><\/div> <\/div> <\/div> <span class=\"ti-stars\"><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/f.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><trustindex-image class=\"ti-star\" data-imgurl=\"https:\/\/cdn.trustindex.io\/assets\/platform\/Booking\/star\/e.svg\" alt=\"Booking\" width=\"17\" height=\"17\" loading=\"lazy\"><\/trustindex-image><span class=\"ti-verified-review\"><span class=\"ti-verified-tooltip\">v\u00e9rifi\u00e9<\/span><\/span><\/span> <div class=\"ti-review-text-container ti-review-content\"><!-- R-CONTENT --><strong>Edullinen viihtyis\u00e4 m\u00f6kki<\/strong>\n\u263aYst\u00e4v\u00e4llinen ja kielitaitoinen rouva oli vastassa. Maisemat kauniit. Saunan l\u00e4mmitys mahdollista, en tehnyt koska saavuin my\u00f6h\u00e4\u00e4n. M\u00f6kiss\u00e4 oli patterin lis\u00e4ksi takka jonka l\u00e4mmitin, sai kosteat vaatteet ripustettua kuivumaan.\n\n\u2639Ilman navigaattoria en olisi l\u00f6yt\u00e4nyt, eli ohjaus tielt\u00e4 saisi olla parempi.<!-- R-CONTENT --><\/div> <span class=\"ti-read-more\" data-container=\".ti-review-content\" data-collapse-text=\"Cacher\" data-open-text=\"Lire la suite\"><\/span> <\/div> <\/div>  <\/div> <div class=\"ti-controls-line\"> <div class=\"dot\"><\/div> <\/div>   <\/div> <\/div> <\/div> <\/template><\/pre><div data-src=\"https:\/\/cdn.trustindex.io\/loader.js?wp-widget\" data-template-id=\"trustindex-booking-widget-html\" data-css-url=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/trustindex-booking-widget.css?1765976254\"><\/div><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-453b034 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"453b034\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-baff8b8\" data-id=\"baff8b8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6f8ed0 elementor-widget elementor-widget-spacer\" data-id=\"e6f8ed0\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b221f4b elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"b221f4b\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 av 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/hiver-04.jpg\" alt=\"hiver-04\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 av 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/hiver-05.jpg\" alt=\"hiver-05\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 av 3\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/hiver-06.jpg\" alt=\"hiver-06\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d6211d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d6211d\" data-element_type=\"section\" data-settings=\"{&quot;ekit_has_onepagescroll_dot&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-5505051\" data-id=\"5505051\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3682902 elementor-widget elementor-widget-tp-heading-title\" data-id=\"3682902\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"tp-heading-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"heading heading_style heading_style6a04bc82da7dd style-6 \" ><div class=\"sub-style \"  ><div class=\"vertical-divider top\"> <\/div><div class=\"head-title \" > <h2  class=\"heading-title   \"   data-hover=\"v\u00e5re andre &lt;br&gt; hundesledeopphold\">v\u00e5re andre <br> hundesledeopphold<\/h2><\/div><div class=\"vertical-divider bottom\"> <\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-b285611\" data-id=\"b285611\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bba8806 elementor-widget elementor-widget-image\" data-id=\"6bba8806\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/racer-01-1024x1024.jpg\" class=\"attachment-large size-large wp-image-16627\" alt=\"\" srcset=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/racer-01-1024x1024.jpg 1024w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/racer-01-300x300.jpg 300w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/racer-01-150x150.jpg 150w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/racer-01-768x768.jpg 768w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/racer-01-700x700.jpg 700w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/racer-01.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5395215e elementor-widget elementor-widget-heading\" data-id=\"5395215e\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Eventyr Racer<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95d2c2e elementor-widget elementor-widget-text-editor\" data-id=\"95d2c2e\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"heading-sub-title \">hundesledeopphold<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5805980 elementor-mobile-align-center elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5805980\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-pulse\" href=\"\/opphold-med-hundeslede\/eventyrreise-racer\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"e7693ca5-bf76-42df-999c-dbc3066cda9e\" data-name=\"Layer 1\" width=\"21.3525\" height=\"10.7197\" viewBox=\"0 0 21.3525 10.7197\"><polygon points=\"21 5.229 21.343 4.865 16.165 0 15.479 0.729 19.737 4.729 0 4.729 0 5.729 19.786 5.729 15.47 10.009 16.175 10.72 21.353 5.584 21 5.229\"><\/polygon><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Les mer<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4a162d6\" data-id=\"4a162d6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-57a2d3e elementor-widget elementor-widget-image\" data-id=\"57a2d3e\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/racer-02-1024x1024.jpg\" class=\"attachment-large size-large wp-image-16631\" alt=\"\" srcset=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/racer-02-1024x1024.jpg 1024w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/racer-02-300x300.jpg 300w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/racer-02-150x150.jpg 150w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/racer-02-768x768.jpg 768w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/racer-02-700x700.jpg 700w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/racer-02.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9f377e elementor-widget elementor-widget-heading\" data-id=\"e9f377e\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">P\u00e5 sporene av Femundl\u00f8pet<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8823ca elementor-widget elementor-widget-text-editor\" data-id=\"e8823ca\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"heading-sub-title \">hundesledeopphold<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5de7da elementor-mobile-align-center elementor-align-center elementor-widget elementor-widget-button\" data-id=\"d5de7da\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-pulse\" href=\"\/opphold-med-hundeslede\/opphold-i-fotsporene-til-femundlopet\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"e7693ca5-bf76-42df-999c-dbc3066cda9e\" data-name=\"Layer 1\" width=\"21.3525\" height=\"10.7197\" viewBox=\"0 0 21.3525 10.7197\"><polygon points=\"21 5.229 21.343 4.865 16.165 0 15.479 0.729 19.737 4.729 0 4.729 0 5.729 19.786 5.729 15.47 10.009 16.175 10.72 21.353 5.584 21 5.229\"><\/polygon><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Les mer<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d1ee633\" data-id=\"d1ee633\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-152a4822 elementor-widget elementor-widget-image\" data-id=\"152a4822\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/hiver-06-1024x1024.jpg\" class=\"attachment-large size-large wp-image-16621\" alt=\"\" srcset=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/hiver-06-1024x1024.jpg 1024w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/hiver-06-300x300.jpg 300w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/hiver-06-150x150.jpg 150w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/hiver-06-768x768.jpg 768w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/hiver-06-700x700.jpg 700w, https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/06\/hiver-06.jpg 1080w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ad670a9 elementor-widget elementor-widget-heading\" data-id=\"6ad670a9\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L\u00e6ring Hundekj\u00f8rer<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e23a117 elementor-widget elementor-widget-text-editor\" data-id=\"7e23a117\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"heading-sub-title \">hundesledeopphold<\/h3>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b3c6c85 elementor-mobile-align-center elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5b3c6c85\" data-element_type=\"widget\" data-settings=\"{&quot;ekit_we_effect_on&quot;:&quot;none&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-pulse\" href=\"\/opphold-med-hundeslede\/opphold-laering-som-hundekjorer\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"e7693ca5-bf76-42df-999c-dbc3066cda9e\" data-name=\"Layer 1\" width=\"21.3525\" height=\"10.7197\" viewBox=\"0 0 21.3525 10.7197\"><polygon points=\"21 5.229 21.343 4.865 16.165 0 15.479 0.729 19.737 4.729 0 4.729 0 5.729 19.786 5.729 15.47 10.009 16.175 10.72 21.353 5.584 21 5.229\"><\/polygon><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Les mer<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Accueil Page #hundesledeopphold Opphold eventyr i Nord sledehunder I de sn\u00f8dekte fjellene blir sledeeventyret episk, og tar oss gjennom ur\u00f8rte landskap for \u00e5 erobre det ukjente. Norge og dets frosne innsj\u00f8er gir et perfekt lerret for \u00e5 nyte gledene ved \u00e5 gli, hvor rommet virker uendelig, og de sn\u00f8dekte omr\u00e5dene glitrer av renhet, og skaper [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":24410,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-24506","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Eventyr i Nord - Escapade Norvegienne<\/title>\n<meta name=\"description\" content=\"Jean-Philippe fra selskapet Escapade Norv\u00e9gienne, en erfaren konkurransedeltaker, vil f\u00f8lge deg p\u00e5 dette eventyret i nord.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/\" \/>\n<meta property=\"og:locale\" content=\"nb_NO\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eventyr i Nord - Escapade Norvegienne\" \/>\n<meta property=\"og:description\" content=\"Jean-Philippe fra selskapet Escapade Norv\u00e9gienne, en erfaren konkurransedeltaker, vil f\u00f8lge deg p\u00e5 dette eventyret i nord.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/\" \/>\n<meta property=\"og:site_name\" content=\"Escapade Norvegienne\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/escapade.norvegienne\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-17T12:44:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/11\/logo-team-pontier.png\" \/>\n\t<meta property=\"og:image:width\" content=\"895\" \/>\n\t<meta property=\"og:image:height\" content=\"780\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Ansl. lesetid\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutter\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"AdvertiserContentArticle\",\"@id\":\"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/\"},\"author\":{\"name\":\"clicainfo\",\"@id\":\"https:\/\/www.escapade-norvegienne.com\/no\/#\/schema\/person\/31780c47572d7c01089f981689fb4de6\"},\"headline\":\"Eventyr i Nord\",\"datePublished\":\"2023-12-10T11:25:58+00:00\",\"dateModified\":\"2025-12-17T12:44:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/\"},\"wordCount\":1239,\"publisher\":{\"@id\":\"https:\/\/www.escapade-norvegienne.com\/no\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/11\/logo-team-pontier.png\",\"inLanguage\":\"nb-NO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/\",\"url\":\"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/\",\"name\":\"Eventyr i Nord - Escapade Norvegienne\",\"isPartOf\":{\"@id\":\"https:\/\/www.escapade-norvegienne.com\/no\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/11\/logo-team-pontier.png\",\"datePublished\":\"2023-12-10T11:25:58+00:00\",\"dateModified\":\"2025-12-17T12:44:57+00:00\",\"description\":\"Jean-Philippe fra selskapet Escapade Norv\u00e9gienne, en erfaren konkurransedeltaker, vil f\u00f8lge deg p\u00e5 dette eventyret i nord.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/#breadcrumb\"},\"inLanguage\":\"nb-NO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nb-NO\",\"@id\":\"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/#primaryimage\",\"url\":\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/11\/logo-team-pontier.png\",\"contentUrl\":\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/11\/logo-team-pontier.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.escapade-norvegienne.com\/no\/accueil\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Opphold med hundeslede\",\"item\":\"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Eventyr i Nord\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.escapade-norvegienne.com\/no\/#website\",\"url\":\"https:\/\/www.escapade-norvegienne.com\/no\/\",\"name\":\"Escapade Norvegienne\",\"description\":\"Your nature | Holiday | In Norway\",\"publisher\":{\"@id\":\"https:\/\/www.escapade-norvegienne.com\/no\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.escapade-norvegienne.com\/no\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nb-NO\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.escapade-norvegienne.com\/no\/#organization\",\"name\":\"Escapade Norvegienne\",\"url\":\"https:\/\/www.escapade-norvegienne.com\/no\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nb-NO\",\"@id\":\"https:\/\/www.escapade-norvegienne.com\/no\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/04\/logo-site2.png\",\"contentUrl\":\"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/04\/logo-site2.png\",\"width\":595,\"height\":212,\"caption\":\"Escapade Norvegienne\"},\"image\":{\"@id\":\"https:\/\/www.escapade-norvegienne.com\/no\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/escapade.norvegienne\",\"https:\/\/www.instagram.com\/escapade_norvegienne\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.escapade-norvegienne.com\/no\/#\/schema\/person\/31780c47572d7c01089f981689fb4de6\",\"name\":\"clicainfo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nb-NO\",\"@id\":\"https:\/\/www.escapade-norvegienne.com\/no\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9adf0820ef7b70e068b40ac82af616d0ef0df906fc90bce66ebaaeedde673fb5?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9adf0820ef7b70e068b40ac82af616d0ef0df906fc90bce66ebaaeedde673fb5?s=96&d=mm&r=g\",\"caption\":\"clicainfo\"},\"sameAs\":[\"https:\/\/www.escapade-norvegienne.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eventyr i Nord - Escapade Norvegienne","description":"Jean-Philippe fra selskapet Escapade Norv\u00e9gienne, en erfaren konkurransedeltaker, vil f\u00f8lge deg p\u00e5 dette eventyret i nord.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/","og_locale":"nb_NO","og_type":"article","og_title":"Eventyr i Nord - Escapade Norvegienne","og_description":"Jean-Philippe fra selskapet Escapade Norv\u00e9gienne, en erfaren konkurransedeltaker, vil f\u00f8lge deg p\u00e5 dette eventyret i nord.","og_url":"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/","og_site_name":"Escapade Norvegienne","article_publisher":"https:\/\/www.facebook.com\/escapade.norvegienne","article_modified_time":"2025-12-17T12:44:57+00:00","og_image":[{"width":895,"height":780,"url":"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/11\/logo-team-pontier.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Ansl. lesetid":"12 minutter"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"AdvertiserContentArticle","@id":"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/#article","isPartOf":{"@id":"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/"},"author":{"name":"clicainfo","@id":"https:\/\/www.escapade-norvegienne.com\/no\/#\/schema\/person\/31780c47572d7c01089f981689fb4de6"},"headline":"Eventyr i Nord","datePublished":"2023-12-10T11:25:58+00:00","dateModified":"2025-12-17T12:44:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/"},"wordCount":1239,"publisher":{"@id":"https:\/\/www.escapade-norvegienne.com\/no\/#organization"},"image":{"@id":"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/11\/logo-team-pontier.png","inLanguage":"nb-NO"},{"@type":"WebPage","@id":"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/","url":"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/","name":"Eventyr i Nord - Escapade Norvegienne","isPartOf":{"@id":"https:\/\/www.escapade-norvegienne.com\/no\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/#primaryimage"},"image":{"@id":"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/#primaryimage"},"thumbnailUrl":"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/11\/logo-team-pontier.png","datePublished":"2023-12-10T11:25:58+00:00","dateModified":"2025-12-17T12:44:57+00:00","description":"Jean-Philippe fra selskapet Escapade Norv\u00e9gienne, en erfaren konkurransedeltaker, vil f\u00f8lge deg p\u00e5 dette eventyret i nord.","breadcrumb":{"@id":"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/#breadcrumb"},"inLanguage":"nb-NO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/"]}]},{"@type":"ImageObject","inLanguage":"nb-NO","@id":"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/#primaryimage","url":"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/11\/logo-team-pontier.png","contentUrl":"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/11\/logo-team-pontier.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/eventyr-i-nord\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.escapade-norvegienne.com\/no\/accueil\/"},{"@type":"ListItem","position":2,"name":"Opphold med hundeslede","item":"https:\/\/www.escapade-norvegienne.com\/no\/opphold-med-hundeslede\/"},{"@type":"ListItem","position":3,"name":"Eventyr i Nord"}]},{"@type":"WebSite","@id":"https:\/\/www.escapade-norvegienne.com\/no\/#website","url":"https:\/\/www.escapade-norvegienne.com\/no\/","name":"Escapade Norvegienne","description":"Your nature | Holiday | In Norway","publisher":{"@id":"https:\/\/www.escapade-norvegienne.com\/no\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.escapade-norvegienne.com\/no\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nb-NO"},{"@type":"Organization","@id":"https:\/\/www.escapade-norvegienne.com\/no\/#organization","name":"Escapade Norvegienne","url":"https:\/\/www.escapade-norvegienne.com\/no\/","logo":{"@type":"ImageObject","inLanguage":"nb-NO","@id":"https:\/\/www.escapade-norvegienne.com\/no\/#\/schema\/logo\/image\/","url":"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/04\/logo-site2.png","contentUrl":"https:\/\/www.escapade-norvegienne.com\/wp-content\/uploads\/2023\/04\/logo-site2.png","width":595,"height":212,"caption":"Escapade Norvegienne"},"image":{"@id":"https:\/\/www.escapade-norvegienne.com\/no\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/escapade.norvegienne","https:\/\/www.instagram.com\/escapade_norvegienne\/"]},{"@type":"Person","@id":"https:\/\/www.escapade-norvegienne.com\/no\/#\/schema\/person\/31780c47572d7c01089f981689fb4de6","name":"clicainfo","image":{"@type":"ImageObject","inLanguage":"nb-NO","@id":"https:\/\/www.escapade-norvegienne.com\/no\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9adf0820ef7b70e068b40ac82af616d0ef0df906fc90bce66ebaaeedde673fb5?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9adf0820ef7b70e068b40ac82af616d0ef0df906fc90bce66ebaaeedde673fb5?s=96&d=mm&r=g","caption":"clicainfo"},"sameAs":["https:\/\/www.escapade-norvegienne.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.escapade-norvegienne.com\/no\/wp-json\/wp\/v2\/pages\/24506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escapade-norvegienne.com\/no\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.escapade-norvegienne.com\/no\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.escapade-norvegienne.com\/no\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escapade-norvegienne.com\/no\/wp-json\/wp\/v2\/comments?post=24506"}],"version-history":[{"count":25,"href":"https:\/\/www.escapade-norvegienne.com\/no\/wp-json\/wp\/v2\/pages\/24506\/revisions"}],"predecessor-version":[{"id":26316,"href":"https:\/\/www.escapade-norvegienne.com\/no\/wp-json\/wp\/v2\/pages\/24506\/revisions\/26316"}],"up":[{"embeddable":true,"href":"https:\/\/www.escapade-norvegienne.com\/no\/wp-json\/wp\/v2\/pages\/24410"}],"wp:attachment":[{"href":"https:\/\/www.escapade-norvegienne.com\/no\/wp-json\/wp\/v2\/media?parent=24506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}